{"id":78410,"date":"2025-02-18T08:43:25","date_gmt":"2025-02-18T07:43:25","guid":{"rendered":"https:\/\/spacesaver.ch\/produkt\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\/"},"modified":"2025-11-21T15:25:15","modified_gmt":"2025-11-21T14:25:15","slug":"kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite","status":"publish","type":"product","link":"https:\/\/spacesaver.ch\/it\/prodotto\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\/","title":{"rendered":"Kit da parete SMARTBett con letto a sagole Standard 140&#215;200 verticale + 2 armadi 50 in rovere Sonoma\/Antracite"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":65548,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1676,1725],"product_tag":[],"pa_ausgeklappte-tiefe":[1720],"pa_breite":[2011],"pa_farbe":[],"pa_front":[1695],"pa_gesamthoehe":[],"pa_gewicht":[],"pa_hohe":[1992],"pa_informationen":[],"pa_korpus":[1682],"pa_lange":[],"pa_lattenrost":[1667],"pa_lieferfrist":[],"pa_lieferzustand":[1668],"pa_liegeflaechte":[1723],"pa_mase":[1724],"pa_material":[1671],"pa_muster-farbe":[],"pa_orientation":[1684],"pa_schaumhoehe":[],"pa_serie":[1718],"pa_sitzhohe":[],"pa_staerke":[],"pa_tiefe":[1685],"pa_versand":[1675],"pa_vieselineanteildewicht":[],"class_list":{"0":"post-78410","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-letti-murphy","7":"product_cat-smartbett-dimensioni-140-cm","8":"pa_lattenrost-classico","9":"pa_liegeflaechte-140-x-200-cm-it","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-yith-composite"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kit da parete SMARTBett con letto a sagole Standard 140x200 verticale + 2 armadi 50 in rovere Sonoma\/Antracite | Spacesaver<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacesaver.ch\/it\/prodotto\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kit da parete SMARTBett con letto a sagole Standard 140x200 verticale + 2 armadi 50 in rovere Sonoma\/Antracite | Spacesaver\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacesaver.ch\/it\/prodotto\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacesaver\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-21T14:25:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacesaver.ch\/wp-content\/uploads\/2025\/02\/smartbett-wohnwand-set-mit-schrankbett-standard-140x200-vertikal-2-x-50-schraenke-eiche-sonoma-anthrazit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/it\\\/prodotto\\\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\\\/\",\"url\":\"https:\\\/\\\/spacesaver.ch\\\/it\\\/prodotto\\\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\\\/\",\"name\":\"Kit da parete SMARTBett con letto a sagole Standard 140x200 verticale + 2 armadi 50 in rovere Sonoma\\\/Antracite | Spacesaver\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/it\\\/prodotto\\\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/it\\\/prodotto\\\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacesaver.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/smartbett-wohnwand-set-mit-schrankbett-standard-140x200-vertikal-2-x-50-schraenke-eiche-sonoma-anthrazit.jpg?wsr\",\"datePublished\":\"2025-02-18T07:43:25+00:00\",\"dateModified\":\"2025-11-21T14:25:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/it\\\/prodotto\\\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacesaver.ch\\\/it\\\/prodotto\\\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/it\\\/prodotto\\\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacesaver.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/smartbett-wohnwand-set-mit-schrankbett-standard-140x200-vertikal-2-x-50-schraenke-eiche-sonoma-anthrazit.jpg?wsr\",\"contentUrl\":\"https:\\\/\\\/spacesaver.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/smartbett-wohnwand-set-mit-schrankbett-standard-140x200-vertikal-2-x-50-schraenke-eiche-sonoma-anthrazit.jpg?wsr\",\"width\":\"1200\",\"height\":\"1200\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/it\\\/prodotto\\\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacesaver.ch\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/spacesaver.ch\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kit da parete SMARTBett con letto a sagole Standard 140&#215;200 verticale + 2 armadi 50 in rovere Sonoma\\\/Antracite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/spacesaver.ch\\\/it\\\/\",\"name\":\"Spacesaver\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacesaver.ch\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/it\\\/#organization\",\"name\":\"Spacesaver | Schrankbetten\",\"url\":\"https:\\\/\\\/spacesaver.ch\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacesaver.ch\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-logo_space.png\",\"contentUrl\":\"https:\\\/\\\/spacesaver.ch\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-logo_space.png\",\"width\":500,\"height\":281,\"caption\":\"Spacesaver | Schrankbetten\"},\"image\":{\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kit da parete SMARTBett con letto a sagole Standard 140x200 verticale + 2 armadi 50 in rovere Sonoma\/Antracite | Spacesaver","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacesaver.ch\/it\/prodotto\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\/","og_locale":"it_IT","og_type":"article","og_title":"Kit da parete SMARTBett con letto a sagole Standard 140x200 verticale + 2 armadi 50 in rovere Sonoma\/Antracite | Spacesaver","og_url":"https:\/\/spacesaver.ch\/it\/prodotto\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\/","og_site_name":"Spacesaver","article_modified_time":"2025-11-21T14:25:15+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/spacesaver.ch\/wp-content\/uploads\/2025\/02\/smartbett-wohnwand-set-mit-schrankbett-standard-140x200-vertikal-2-x-50-schraenke-eiche-sonoma-anthrazit.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spacesaver.ch\/it\/prodotto\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\/","url":"https:\/\/spacesaver.ch\/it\/prodotto\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\/","name":"Kit da parete SMARTBett con letto a sagole Standard 140x200 verticale + 2 armadi 50 in rovere Sonoma\/Antracite | Spacesaver","isPartOf":{"@id":"https:\/\/spacesaver.ch\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacesaver.ch\/it\/prodotto\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\/#primaryimage"},"image":{"@id":"https:\/\/spacesaver.ch\/it\/prodotto\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\/#primaryimage"},"thumbnailUrl":"https:\/\/spacesaver.ch\/wp-content\/uploads\/2025\/02\/smartbett-wohnwand-set-mit-schrankbett-standard-140x200-vertikal-2-x-50-schraenke-eiche-sonoma-anthrazit.jpg?wsr","datePublished":"2025-02-18T07:43:25+00:00","dateModified":"2025-11-21T14:25:15+00:00","breadcrumb":{"@id":"https:\/\/spacesaver.ch\/it\/prodotto\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacesaver.ch\/it\/prodotto\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/spacesaver.ch\/it\/prodotto\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\/#primaryimage","url":"https:\/\/spacesaver.ch\/wp-content\/uploads\/2025\/02\/smartbett-wohnwand-set-mit-schrankbett-standard-140x200-vertikal-2-x-50-schraenke-eiche-sonoma-anthrazit.jpg?wsr","contentUrl":"https:\/\/spacesaver.ch\/wp-content\/uploads\/2025\/02\/smartbett-wohnwand-set-mit-schrankbett-standard-140x200-vertikal-2-x-50-schraenke-eiche-sonoma-anthrazit.jpg?wsr","width":"1200","height":"1200"},{"@type":"BreadcrumbList","@id":"https:\/\/spacesaver.ch\/it\/prodotto\/kit-da-parete-smartbett-con-letto-a-sagole-standard-140x200-verticale-2-armadi-50-in-rovere-sonoma-antracite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacesaver.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/spacesaver.ch\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Kit da parete SMARTBett con letto a sagole Standard 140&#215;200 verticale + 2 armadi 50 in rovere Sonoma\/Antracite"}]},{"@type":"WebSite","@id":"https:\/\/spacesaver.ch\/it\/#website","url":"https:\/\/spacesaver.ch\/it\/","name":"Spacesaver","description":"","publisher":{"@id":"https:\/\/spacesaver.ch\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacesaver.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/spacesaver.ch\/it\/#organization","name":"Spacesaver | Schrankbetten","url":"https:\/\/spacesaver.ch\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/spacesaver.ch\/it\/#\/schema\/logo\/image\/","url":"https:\/\/spacesaver.ch\/wp-content\/uploads\/2020\/03\/cropped-logo_space.png","contentUrl":"https:\/\/spacesaver.ch\/wp-content\/uploads\/2020\/03\/cropped-logo_space.png","width":500,"height":281,"caption":"Spacesaver | Schrankbetten"},"image":{"@id":"https:\/\/spacesaver.ch\/it\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/product\/78410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/media\/65548"}],"wp:attachment":[{"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/media?parent=78410"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/product_brand?post=78410"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/product_cat?post=78410"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/product_tag?post=78410"},{"taxonomy":"pa_ausgeklappte-tiefe","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_ausgeklappte-tiefe?post=78410"},{"taxonomy":"pa_breite","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_breite?post=78410"},{"taxonomy":"pa_farbe","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_farbe?post=78410"},{"taxonomy":"pa_front","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_front?post=78410"},{"taxonomy":"pa_gesamthoehe","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_gesamthoehe?post=78410"},{"taxonomy":"pa_gewicht","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_gewicht?post=78410"},{"taxonomy":"pa_hohe","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_hohe?post=78410"},{"taxonomy":"pa_informationen","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_informationen?post=78410"},{"taxonomy":"pa_korpus","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_korpus?post=78410"},{"taxonomy":"pa_lange","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_lange?post=78410"},{"taxonomy":"pa_lattenrost","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_lattenrost?post=78410"},{"taxonomy":"pa_lieferfrist","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_lieferfrist?post=78410"},{"taxonomy":"pa_lieferzustand","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_lieferzustand?post=78410"},{"taxonomy":"pa_liegeflaechte","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_liegeflaechte?post=78410"},{"taxonomy":"pa_mase","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_mase?post=78410"},{"taxonomy":"pa_material","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_material?post=78410"},{"taxonomy":"pa_muster-farbe","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_muster-farbe?post=78410"},{"taxonomy":"pa_orientation","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_orientation?post=78410"},{"taxonomy":"pa_schaumhoehe","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_schaumhoehe?post=78410"},{"taxonomy":"pa_serie","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_serie?post=78410"},{"taxonomy":"pa_sitzhohe","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_sitzhohe?post=78410"},{"taxonomy":"pa_staerke","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_staerke?post=78410"},{"taxonomy":"pa_tiefe","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_tiefe?post=78410"},{"taxonomy":"pa_versand","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_versand?post=78410"},{"taxonomy":"pa_vieselineanteildewicht","embeddable":true,"href":"https:\/\/spacesaver.ch\/it\/wp-json\/wp\/v2\/pa_vieselineanteildewicht?post=78410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}