{"id":76112,"date":"2025-02-19T12:39:02","date_gmt":"2025-02-19T11:39:02","guid":{"rendered":"https:\/\/spacesaver.ch\/produkt\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\/"},"modified":"2025-11-21T13:34:58","modified_gmt":"2025-11-21T12:34:58","slug":"murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame","status":"publish","type":"product","link":"https:\/\/spacesaver.ch\/en\/product\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\/","title":{"rendered":"Murphy bed M1 180&#215;200 Vertical Pearl Grey\/Kaiserberg Oak incl. Upholstered frame"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":75017,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1386,1869],"product_tag":[],"pa_ausgeklappte-tiefe":[1870],"pa_breite":[1871],"pa_farbe":[],"pa_front":[1894],"pa_gesamthoehe":[],"pa_gewicht":[],"pa_hohe":[1872],"pa_informationen":[],"pa_korpus":[1904],"pa_lange":[],"pa_lattenrost":[1377],"pa_lieferfrist":[],"pa_lieferzustand":[1378],"pa_liegeflaechte":[1826],"pa_mase":[1873],"pa_material":[1381],"pa_muster-farbe":[],"pa_orientation":[1392],"pa_schaumhoehe":[],"pa_serie":[1417],"pa_sitzhohe":[],"pa_staerke":[],"pa_tiefe":[1384],"pa_versand":[1385],"pa_vieselineanteildewicht":[],"class_list":{"0":"post-76112","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-murphy-beds","7":"product_cat-smartbed-180-cm","8":"pa_lattenrost-classic-en","9":"pa_liegeflaechte-180-x-200-cm","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-yith-composite"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Murphy bed M1 180x200 Vertical Pearl Grey\/Kaiserberg Oak incl. Upholstered frame | Spacesaver<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spacesaver.ch\/en\/product\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Murphy bed M1 180x200 Vertical Pearl Grey\/Kaiserberg Oak incl. Upholstered frame | Spacesaver\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spacesaver.ch\/en\/product\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\/\" \/>\n<meta property=\"og:site_name\" content=\"Spacesaver\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-21T12:34:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spacesaver.ch\/wp-content\/uploads\/2025\/02\/schrankbett-m1-180x200-vertikal-perlgrau-kaiserberg-eiche-inklpolsterrahmen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/en\\\/product\\\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\\\/\",\"url\":\"https:\\\/\\\/spacesaver.ch\\\/en\\\/product\\\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\\\/\",\"name\":\"Murphy bed M1 180x200 Vertical Pearl Grey\\\/Kaiserberg Oak incl. Upholstered frame | Spacesaver\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/en\\\/product\\\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/en\\\/product\\\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spacesaver.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/schrankbett-m1-180x200-vertikal-perlgrau-kaiserberg-eiche-inklpolsterrahmen.jpg?wsr\",\"datePublished\":\"2025-02-19T11:39:02+00:00\",\"dateModified\":\"2025-11-21T12:34:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/en\\\/product\\\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spacesaver.ch\\\/en\\\/product\\\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/en\\\/product\\\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spacesaver.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/schrankbett-m1-180x200-vertikal-perlgrau-kaiserberg-eiche-inklpolsterrahmen.jpg?wsr\",\"contentUrl\":\"https:\\\/\\\/spacesaver.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/schrankbett-m1-180x200-vertikal-perlgrau-kaiserberg-eiche-inklpolsterrahmen.jpg?wsr\",\"width\":\"1200\",\"height\":\"1200\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/en\\\/product\\\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spacesaver.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\\\/\\\/spacesaver.ch\\\/en\\\/store\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Murphy bed M1 180&#215;200 Vertical Pearl Grey\\\/Kaiserberg Oak incl. Upholstered frame\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spacesaver.ch\\\/en\\\/\",\"name\":\"Spacesaver\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spacesaver.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/en\\\/#organization\",\"name\":\"Spacesaver | Schrankbetten\",\"url\":\"https:\\\/\\\/spacesaver.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spacesaver.ch\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-logo_space.png\",\"contentUrl\":\"https:\\\/\\\/spacesaver.ch\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-logo_space.png\",\"width\":500,\"height\":281,\"caption\":\"Spacesaver | Schrankbetten\"},\"image\":{\"@id\":\"https:\\\/\\\/spacesaver.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Murphy bed M1 180x200 Vertical Pearl Grey\/Kaiserberg Oak incl. Upholstered frame | Spacesaver","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spacesaver.ch\/en\/product\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\/","og_locale":"en_US","og_type":"article","og_title":"Murphy bed M1 180x200 Vertical Pearl Grey\/Kaiserberg Oak incl. Upholstered frame | Spacesaver","og_url":"https:\/\/spacesaver.ch\/en\/product\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\/","og_site_name":"Spacesaver","article_modified_time":"2025-11-21T12:34:58+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/spacesaver.ch\/wp-content\/uploads\/2025\/02\/schrankbett-m1-180x200-vertikal-perlgrau-kaiserberg-eiche-inklpolsterrahmen.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spacesaver.ch\/en\/product\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\/","url":"https:\/\/spacesaver.ch\/en\/product\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\/","name":"Murphy bed M1 180x200 Vertical Pearl Grey\/Kaiserberg Oak incl. Upholstered frame | Spacesaver","isPartOf":{"@id":"https:\/\/spacesaver.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spacesaver.ch\/en\/product\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\/#primaryimage"},"image":{"@id":"https:\/\/spacesaver.ch\/en\/product\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\/#primaryimage"},"thumbnailUrl":"https:\/\/spacesaver.ch\/wp-content\/uploads\/2025\/02\/schrankbett-m1-180x200-vertikal-perlgrau-kaiserberg-eiche-inklpolsterrahmen.jpg?wsr","datePublished":"2025-02-19T11:39:02+00:00","dateModified":"2025-11-21T12:34:58+00:00","breadcrumb":{"@id":"https:\/\/spacesaver.ch\/en\/product\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spacesaver.ch\/en\/product\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spacesaver.ch\/en\/product\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\/#primaryimage","url":"https:\/\/spacesaver.ch\/wp-content\/uploads\/2025\/02\/schrankbett-m1-180x200-vertikal-perlgrau-kaiserberg-eiche-inklpolsterrahmen.jpg?wsr","contentUrl":"https:\/\/spacesaver.ch\/wp-content\/uploads\/2025\/02\/schrankbett-m1-180x200-vertikal-perlgrau-kaiserberg-eiche-inklpolsterrahmen.jpg?wsr","width":"1200","height":"1200"},{"@type":"BreadcrumbList","@id":"https:\/\/spacesaver.ch\/en\/product\/murphy-bed-m1-180x200-vertical-pearl-grey-kaiserberg-oak-incl-upholstered-frame\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spacesaver.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Store","item":"https:\/\/spacesaver.ch\/en\/store\/"},{"@type":"ListItem","position":3,"name":"Murphy bed M1 180&#215;200 Vertical Pearl Grey\/Kaiserberg Oak incl. Upholstered frame"}]},{"@type":"WebSite","@id":"https:\/\/spacesaver.ch\/en\/#website","url":"https:\/\/spacesaver.ch\/en\/","name":"Spacesaver","description":"","publisher":{"@id":"https:\/\/spacesaver.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spacesaver.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spacesaver.ch\/en\/#organization","name":"Spacesaver | Schrankbetten","url":"https:\/\/spacesaver.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spacesaver.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spacesaver.ch\/wp-content\/uploads\/2020\/03\/cropped-logo_space.png","contentUrl":"https:\/\/spacesaver.ch\/wp-content\/uploads\/2020\/03\/cropped-logo_space.png","width":500,"height":281,"caption":"Spacesaver | Schrankbetten"},"image":{"@id":"https:\/\/spacesaver.ch\/en\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/product\/76112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/media\/75017"}],"wp:attachment":[{"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/media?parent=76112"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/product_brand?post=76112"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/product_cat?post=76112"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/product_tag?post=76112"},{"taxonomy":"pa_ausgeklappte-tiefe","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_ausgeklappte-tiefe?post=76112"},{"taxonomy":"pa_breite","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_breite?post=76112"},{"taxonomy":"pa_farbe","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_farbe?post=76112"},{"taxonomy":"pa_front","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_front?post=76112"},{"taxonomy":"pa_gesamthoehe","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_gesamthoehe?post=76112"},{"taxonomy":"pa_gewicht","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_gewicht?post=76112"},{"taxonomy":"pa_hohe","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_hohe?post=76112"},{"taxonomy":"pa_informationen","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_informationen?post=76112"},{"taxonomy":"pa_korpus","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_korpus?post=76112"},{"taxonomy":"pa_lange","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_lange?post=76112"},{"taxonomy":"pa_lattenrost","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_lattenrost?post=76112"},{"taxonomy":"pa_lieferfrist","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_lieferfrist?post=76112"},{"taxonomy":"pa_lieferzustand","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_lieferzustand?post=76112"},{"taxonomy":"pa_liegeflaechte","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_liegeflaechte?post=76112"},{"taxonomy":"pa_mase","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_mase?post=76112"},{"taxonomy":"pa_material","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_material?post=76112"},{"taxonomy":"pa_muster-farbe","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_muster-farbe?post=76112"},{"taxonomy":"pa_orientation","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_orientation?post=76112"},{"taxonomy":"pa_schaumhoehe","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_schaumhoehe?post=76112"},{"taxonomy":"pa_serie","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_serie?post=76112"},{"taxonomy":"pa_sitzhohe","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_sitzhohe?post=76112"},{"taxonomy":"pa_staerke","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_staerke?post=76112"},{"taxonomy":"pa_tiefe","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_tiefe?post=76112"},{"taxonomy":"pa_versand","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_versand?post=76112"},{"taxonomy":"pa_vieselineanteildewicht","embeddable":true,"href":"https:\/\/spacesaver.ch\/en\/wp-json\/wp\/v2\/pa_vieselineanteildewicht?post=76112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}